{"id":11154,"date":"2022-08-15T08:00:00","date_gmt":"2022-08-15T06:00:00","guid":{"rendered":"https:\/\/brm-conseil.fr\/?p=11154"},"modified":"2023-01-07T17:09:57","modified_gmt":"2023-01-07T16:09:57","slug":"occupazione-oftalmologo-in-francia-come-trovare-lavoro","status":"publish","type":"post","link":"https:\/\/brm-conseil.fr\/it\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/","title":{"rendered":"Offerte di lavoro per oftalmologi in Francia: come trovare una posizione?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.10.7&Prime; background_image=\u00a0\u00bbhttps:\/\/brm-conseil.fr\/wp-content\/uploads\/2022\/08\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; background_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb custom_margin=\u00a0\u00bb-150px||\u00a0\u00bb custom_padding=\u00a0\u00bb|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; background_color=\u00a0\u00bb#0c71c3&Prime; custom_padding=\u00a0\u00bb30px|20px|30px|20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_post_title author=\u00a0\u00bboff\u00a0\u00bb date_format=\u00a0\u00bbj F Y\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.0.3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_text_align=\u00a0\u00bbleft\u00a0\u00bb title_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb title_font_size=\u00a0\u00bb30px\u00a0\u00bb meta_font=\u00a0\u00bb||||||||\u00a0\u00bb meta_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb title_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb title_font_size_phone=\u00a0\u00bb\u00a0\u00bb title_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.0.3&Prime; custom_margin=\u00a0\u00bb-100px||-30px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb3.25.2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.0.3&Prime; custom_margin=\u00a0\u00bb-9px|100px||100px||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Vous avez fini vos 11 ou 12 ans d\u2019\u00e9tudes sup\u00e9rieures et vous voil\u00e0 fra\u00eechement dipl\u00f4m\u00e9 en ophtalmologie. F\u00e9licitations ! Vous devez trouver un point de chute pour votre d\u00e9but de carri\u00e8re de praticien. Peut-\u00eatre \u00eates-vous un m\u00e9decin d\u00e9j\u00e0 exp\u00e9riment\u00e9, mais vous avez envie de nouveaux challenges. Avant de postuler pour un<span>\u00a0<\/span><a href=\"https:\/\/brm-conseil.fr\/emploi-ophtalmologue\/\"><strong>emploi en ophtalmologie<\/strong><\/a><span>\u00a0<\/span>en France, vous devez trouver VOS r\u00e9ponses \u00e0 de nombreuses questions. En voici un tour d\u2019horizon.<\/p>\n<h2 style=\"text-align: justify;\">Petit rappel sur l\u2019\u00e9tat de l&rsquo;ophtalmologie en France<\/h2>\n<p style=\"text-align: justify;\">En France fin 2020, vous \u00e9tiez 5826 ophtalmologues en exercice (chiffres de la DREES), soit une moyenne de 8,8 praticiens sp\u00e9cialistes de la vision et de l\u2019\u0153il pour 100 000 habitants. Cela n\u2019a jamais \u00e9t\u00e9 aussi peu. La chute des effectifs s\u2019acc\u00e9l\u00e8re avec des d\u00e9parts en retraite massifs attendus dans les ann\u00e9es \u00e0 venir et toujours seulement 120 nouveaux m\u00e9decins \u00e0 sortir chaque ann\u00e9e des facult\u00e9s de m\u00e9decine.<\/p>\n<p style=\"text-align: justify;\">Aujourd\u2019hui, seulement 16 % des m\u00e9decins en ophtalmologie exercent avec le statut de salari\u00e9, 23 % sont en exercice mixte et 61 % en statut lib\u00e9ral pur. En outre, ces chiffres cachent bien d\u2019autres r\u00e9alit\u00e9s : des disparit\u00e9s entre r\u00e9gions et au sein d\u2019une m\u00eame r\u00e9gion, mais aussi une p\u00e9nurie cruelle de professionnels partout. La moyenne d\u2019\u00e2ge des m\u00e9decins de cette sp\u00e9cialit\u00e9 ne cesse d\u2019augmenter (plus de 52 ans aujourd\u2019hui).\u00a0<\/p>\n<p style=\"text-align: justify;\">Or la demande des soins oculaires explose. En effet, le recours de la population \u00e0 votre sp\u00e9cialit\u00e9 a tripl\u00e9 en 25 ans. Le vieillissement de la population augmente le besoin en soins pour la cataracte, les glaucomes ou la d\u00e9g\u00e9n\u00e9rescence maculaire. Vous le savez, en tant que jeune (ou moins jeune) praticien, ce panorama vous donne toutes les cartes en main pour choisir r\u00e9ellement votre carri\u00e8re professionnelle. Vous \u00eates attendus partout.<\/p>\n<h2 style=\"text-align: justify;\">Comment ai-je envie d\u2019exercer mon\u00a0m\u00e9tier d\u2019ophtalmologiste ?\u00a0<\/h2>\n<h3 style=\"text-align: justify;\">Le choix du statut<\/h3>\n<p style=\"text-align: justify;\">La premi\u00e8re des questions \u00e0 laquelle vous devez r\u00e9pondre (au-del\u00e0 du lieu), c\u2019est celle du statut souhait\u00e9. L\u2019installation au sein d\u2019un cabinet lib\u00e9ral est un pas important \u00e0 franchir, une aventure au long cours, non seulement pour le jeune m\u00e9decin, mais aussi pour sa famille. Apr\u00e8s quelques ann\u00e9es dans une ville universitaire, le d\u00e9part vers un centre plus petit est \u00e0 faire en famille. C\u2019est aussi un choix de vie.<\/p>\n<p style=\"text-align: justify;\">Afin d\u2019\u00eatre s\u00fbr du territoire \u00e0 investir, de votre futur bassin d\u2019activit\u00e9 et de son potentiel, pourquoi ne pas tester un emploi salari\u00e9 ou un remplacement dans un \u00e9tablissement de sant\u00e9 priv\u00e9 ou public ? Les<span>\u00a0<\/span><a href=\"https:\/\/brm-conseil.fr\/emploi-ophtalmologue\/\"><strong>offres d\u2019emploi en ophtalmologie<\/strong><\/a><span>\u00a0<\/span>salari\u00e9 sont nombreuses sur les agr\u00e9gateurs d\u2019annonces ou sur les sites sp\u00e9cialis\u00e9s. L\u2019avantage de ce statut est que vous vous concentrez sur la pratique professionnelle. Vous n\u2019avez pas les contraintes de la gestion au quotidien d\u2019une structure lib\u00e9rale (charges, administration, personnel, locaux, etc.). Les r\u00e9mun\u00e9rations sont aujourd\u2019hui tr\u00e8s attractives, les avantages sont ceux du salariat. Pour attirer de jeunes praticiens, les structures font des efforts financiers, la libert\u00e9 de planning et d\u2019horaires. Tout cela peut \u00eatre tr\u00e8s int\u00e9ressant quand on ne veut pas trop sacrifier sa vie personnelle.\u00a0<\/p>\n<h3 style=\"text-align: justify;\">Le choix de l\u2019environnement<\/h3>\n<p style=\"text-align: justify;\">Apr\u00e8s quelques ann\u00e9es de stage et de pratique aux c\u00f4t\u00e9s de praticiens universitaires, vous devez avoir une id\u00e9e de ce qui vous convient vraiment. Seriez-vous plus \u00e0 l\u2019aise dans une petite structure avec une patient\u00e8le de tous les \u00e2ges ? Est-ce que votre \u00e9panouissement passe par une pratique dans un grand centre plus sp\u00e9cialis\u00e9 avec une activit\u00e9 chirurgicale sur les pathologies du vieillissement ? Souhaitez-vous disposer de temps pour vous ? Pour vous former ou profiter de votre vie personnelle ? Autant de questions qui d\u00e9terminent vos choix.\u00a0<\/p>\n<h3 style=\"text-align: justify;\">Le choix des conditions de travail<\/h3>\n<p style=\"text-align: justify;\">Les <a href=\"https:\/\/brm-conseil.fr\/annonces-medicales-dentaires\/\">annonces m\u00e9dicales<\/a> sont parfois tr\u00e8s laconiques sur certains aspects comme les conditions mat\u00e9rielles d\u2019exercice de la sp\u00e9cialit\u00e9 d\u2019ophtalmologie. C\u2019est pourtant essentiel, notamment si vous vous orientez vers la reprise d\u2019un cabinet lib\u00e9ral. Le plateau technique, l\u2019acc\u00e8s \u00e0 un bloc si vous faites de la chirurgie de l\u2019\u0153il, l\u2019\u00e9quipement, le personnel, les locaux : r\u00e9fl\u00e9chissez-y, ne vous pr\u00e9cipitez pas.<\/p>\n<p style=\"text-align: justify;\">Si vous vous engagez au sein d\u2019un \u00e9tablissement de soins et de sant\u00e9, creusez tous les points importants. La composition des \u00e9quipes, les sp\u00e9cialit\u00e9s propos\u00e9es, la philosophie, la sant\u00e9 financi\u00e8re, les valeurs de la structure, l\u2019environnement m\u00e9dical sont \u00e0 connaitre autant que les contraintes li\u00e9es au poste\u2026 Ces points importants sont \u00e0 clarifier avant l\u2019engagement, surtout si vous l\u2019imaginez durable.\u00a0<\/p>\n<h2 style=\"text-align: justify;\">Comment puis-je me faire accompagner ?<\/h2>\n<p style=\"text-align: justify;\">Une fois \u00e9tablis vos souhaits et vos crit\u00e8res, vous gagnerez du temps en faisant confiance \u00e0 un<span>\u00a0<\/span><strong>cabinet de recrutement m\u00e9dical<\/strong><span>\u00a0<\/span>comme BRM Conseil (bureau de <a href=\"https:\/\/brm-conseil.fr\/emploi-medecin-generaliste\/\">recrutement de m\u00e9decins<\/a>). Ses experts \u0153uvrent exclusivement dans le placement de m\u00e9decins. Depuis plus d\u2019une d\u00e9cennie, ils ont construit un vaste r\u00e9seau de m\u00e9decins, de directions d\u2019\u00e9tablissements recruteurs. Un tel service facilite grandement votre acc\u00e8s \u00e0 l\u2019information, primordial dans la<span>\u00a0<\/span><strong>recherche d\u2019emploi m\u00e9dical<\/strong>. Les conseillers de BRM Conseil offrent un service rapide, cibl\u00e9 et personnalis\u00e9 au b\u00e9n\u00e9fice de tous, recruteurs comme candidats.<\/p>\n<p style=\"text-align: justify;\">Un cabinet de placement peut aussi vous aider \u00e0 affiner votre projet professionnel et personnel. Il vous accompagnera pour interroger vos crit\u00e8res en fonction de votre situation.\u00a0<\/p>\n<p style=\"text-align: justify;\">Si votre projet implique aussi votre conjoint, voire vos enfants, les enjeux ne seront pas les m\u00eames. Le lieu d\u2019implantation sera d\u2019autant plus important. Avec de jeunes enfants, un poste dans un petit centre urbain proche des grands axes, mais sans les contraintes de la vie quotidienne tr\u00e8s urbaine peut \u00eatre une vraie opportunit\u00e9. En fonction de l\u2019activit\u00e9 professionnelle de votre conjoint, une r\u00e9gion plus qu\u2019une autre peut s\u2019imposer. Vous avez la chance d\u2019exercer une profession o\u00f9 vous avez l\u2019embarras du choix.\u00a0<\/p>\n<h2 style=\"text-align: justify;\">Quels r\u00e9seaux peuvent m\u2019\u00eatre utiles ?<\/h2>\n<p style=\"text-align: justify;\">Dans le monde de l\u2019ophtalmologie fran\u00e7aise, le r\u00e9seau a un nom. Il s\u2019appelle le SNOF : syndicat national des ophtalmologistes de France. Y adh\u00e9rer, c\u2019est b\u00e9n\u00e9ficier des derni\u00e8res actualit\u00e9s en sant\u00e9 publique, des derni\u00e8res nouvelles scientifiques. Le SNOF organise aussi des rencontres professionnelles, accompagne les professionnels et les repr\u00e9sente. Le site est une mine d\u2019information pour ses adh\u00e9rents avec des \u00e9tudes de cas, des <a href=\"https:\/\/brm-conseil.fr\/emploi-ophtalmologue\/\">annonces de recrutements<\/a> tr\u00e8s diverses, des ventes de mat\u00e9riels d\u2019occasion. C\u2019est ici aussi que vous trouverez les annonces d\u2019offres de cessions ou d\u2019associations de confr\u00e8res et de cons\u0153urs les plus int\u00e9ressantes et compl\u00e8tes. La plupart proposent une p\u00e9riode de \u00ab test \u00bb sous la forme de remplacement temporaire.<\/p>\n<p style=\"text-align: justify;\">Enfin, rappelons que votre r\u00e9seau informel des amis, des cercles sportifs, culturels, anciens confr\u00e8res et cons\u0153urs est aussi important et souvent le plus efficace pour<span>\u00a0<\/span><strong>trouver un poste d\u2019ophtalmologue<\/strong><span>\u00a0<\/span>en France.<\/p>\n<p style=\"text-align: justify;\">N&rsquo;oubliez pas aussi de consulter les donn\u00e9es publiques \u00e0 jour de d\u00e9mographie m\u00e9dicale comme CartoS@nt\u00e9 ou la cartographie interactive du Conseil national de l&rsquo;Ordre des M\u00e9decins. Ils vous permettent de dresser un portrait assez pr\u00e9cis de l&rsquo;environnement m\u00e9dical d&rsquo;une ville.<\/p>\n<p style=\"text-align: justify;\">En bref, quel que soit votre projet, la situation de l\u2019ophtalmologie en France vous est favorable si vous<span>\u00a0<\/span><strong>cherchez un poste<\/strong>. Avant de r\u00e9pondre aux offres trop all\u00e9chantes, veillez \u00e0 bien analyser votre projet de vie et n\u2019h\u00e9sitez pas \u00e0 \u00e9changer et \u00e0 vous faire accompagner pour prendre la bonne d\u00e9cision.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.0.3&Prime; custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.0.3&Prime; background_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.0.3&Prime; background_color=\u00a0\u00bb#0c71c3&Prime; custom_padding=\u00a0\u00bb20px|15px|20px|15px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.0.3&Prime; text_font=\u00a0\u00bb|800|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center\">D\u00e9couvrez toutes nos offres d\u2019emploi destin\u00e9es aux m\u00e9decins et professionnels de la sant\u00e9.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/brm-conseil.fr\/offres-demploi-sante\/\u00a0\u00bb button_text=\u00a0\u00bbNos offres d&#8217;emplois\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.0.3&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#0c71c3&Prime; button_bg_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_border_width=\u00a0\u00bb2px\u00a0\u00bb button_border_radius=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.0.3&Prime; background_color=\u00a0\u00bb#d6d6d6&Prime; custom_padding=\u00a0\u00bb20px|15px|20px|15px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.0.3&Prime; text_font=\u00a0\u00bb|800|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center\">Vous souhaitez recruter un m\u00e9decin ? BRM Conseil se charge de vous en trouver un !<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/brm-conseil.fr\/espace-recruteurs-brm-conseil\/#Formulaire_recruteur\u00a0\u00bb button_text=\u00a0\u00bbconfiez-nous votre projet de recrutement\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.0.3&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_border_radius=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L'oftalmologia soffre di una carenza di medici come altre specialit\u00e0. I professionisti che si spostano hanno l'imbarazzo della scelta<\/p>","protected":false},"author":6,"featured_media":11155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[135],"tags":[1779,1775,1515,1777,1778,1776,1517],"class_list":["post-11154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ophtalmologue","tag-annonce-ophtalmo-salarie","tag-emploi-ophtalmologiste","tag-emploi-ophtalmologue","tag-emploi-ophtalmologue-liberal","tag-job-en-ophtalmologie","tag-reseau-professionnel-ophtalmologie","tag-snof"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emploi d&#039;ophtalmologue : comment trouver un poste ? - BRM Conseil<\/title>\n<meta name=\"description\" content=\"L\u2019ophtalmologie souffre d\u2019une p\u00e9nurie de praticiens comme d\u2019autres sp\u00e9cialit\u00e9s. Les praticiens en mobilit\u00e9 ont l\u2019embarras du choix\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emploi d&#039;ophtalmologue : comment trouver un poste ? - BRM Conseil\" \/>\n<meta property=\"og:description\" content=\"L\u2019ophtalmologie souffre d\u2019une p\u00e9nurie de praticiens comme d\u2019autres sp\u00e9cialit\u00e9s. Les praticiens en mobilit\u00e9 ont l\u2019embarras du choix\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154\" \/>\n<meta property=\"og:site_name\" content=\"BRM Conseil\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-15T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-07T16:09:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2020\/01\/LinkedIn_Brm-Conseil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"genone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"genone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/\"},\"author\":{\"name\":\"genone\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/person\\\/306310a2b7c316650384cfd4a81211ed\"},\"headline\":\"Emploi ophtalmologue en France : comment trouver un poste ?\",\"datePublished\":\"2022-08-15T06:00:00+00:00\",\"dateModified\":\"2023-01-07T16:09:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/\"},\"wordCount\":1792,\"publisher\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg\",\"keywords\":[\"annonce ophtalmo salari\u00e9\",\"emploi ophtalmologiste\",\"emploi ophtalmologue\",\"emploi ophtalmologue lib\u00e9ral\",\"job en ophtalmologie\",\"r\u00e9seau professionnel ophtalmologie\",\"Snof\"],\"articleSection\":[\"Ophtalmologue\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/\",\"name\":\"Emploi d'ophtalmologue : comment trouver un poste ? - BRM Conseil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg\",\"datePublished\":\"2022-08-15T06:00:00+00:00\",\"dateModified\":\"2023-01-07T16:09:57+00:00\",\"description\":\"L\u2019ophtalmologie souffre d\u2019une p\u00e9nurie de praticiens comme d\u2019autres sp\u00e9cialit\u00e9s. Les praticiens en mobilit\u00e9 ont l\u2019embarras du choix\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg\",\"contentUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg\",\"width\":1500,\"height\":956,\"caption\":\"ophtalmologue auscultant un patient dans un cabinet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/2022\\\/08\\\/15\\\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emploi ophtalmologue en France : comment trouver un poste ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\",\"name\":\"BrmConseil\",\"description\":\"Sp\u00e9cialiste du recrutement m\u00e9dical\",\"publisher\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\",\"name\":\"BRM Conseil\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-brmconseil.png\",\"contentUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-brmconseil.png\",\"width\":420,\"height\":66,\"caption\":\"BRM Conseil\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/person\\\/306310a2b7c316650384cfd4a81211ed\",\"name\":\"genone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"caption\":\"genone\"},\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/author\\\/genone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emploi d'ophtalmologue : comment trouver un poste ? - BRM Conseil","description":"L'oftalmologia soffre di una carenza di medici come altre specialit\u00e0. I professionisti che si spostano hanno l'imbarazzo della scelta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154","og_locale":"it_IT","og_type":"article","og_title":"Emploi d'ophtalmologue : comment trouver un poste ? - BRM Conseil","og_description":"L\u2019ophtalmologie souffre d\u2019une p\u00e9nurie de praticiens comme d\u2019autres sp\u00e9cialit\u00e9s. Les praticiens en mobilit\u00e9 ont l\u2019embarras du choix","og_url":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154","og_site_name":"BRM Conseil","article_published_time":"2022-08-15T06:00:00+00:00","article_modified_time":"2023-01-07T16:09:57+00:00","og_image":[{"width":1500,"height":956,"url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2020\/01\/LinkedIn_Brm-Conseil.png","type":"image\/jpeg"}],"author":"genone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"genone","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#article","isPartOf":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/"},"author":{"name":"genone","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/person\/306310a2b7c316650384cfd4a81211ed"},"headline":"Emploi ophtalmologue en France : comment trouver un poste ?","datePublished":"2022-08-15T06:00:00+00:00","dateModified":"2023-01-07T16:09:57+00:00","mainEntityOfPage":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/"},"wordCount":1792,"publisher":{"@id":"https:\/\/brm-conseil.fr\/fr\/#organization"},"image":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#primaryimage"},"thumbnailUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2022\/08\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg","keywords":["annonce ophtalmo salari\u00e9","emploi ophtalmologiste","emploi ophtalmologue","emploi ophtalmologue lib\u00e9ral","job en ophtalmologie","r\u00e9seau professionnel ophtalmologie","Snof"],"articleSection":["Ophtalmologue"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/","url":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/","name":"Emploi d'ophtalmologue : comment trouver un poste ? - BRM Conseil","isPartOf":{"@id":"https:\/\/brm-conseil.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#primaryimage"},"image":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#primaryimage"},"thumbnailUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2022\/08\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg","datePublished":"2022-08-15T06:00:00+00:00","dateModified":"2023-01-07T16:09:57+00:00","description":"L'oftalmologia soffre di una carenza di medici come altre specialit\u00e0. I professionisti che si spostano hanno l'imbarazzo della scelta","breadcrumb":{"@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#primaryimage","url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2022\/08\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg","contentUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2022\/08\/female-ophthalmologist-examining-mature-mans-eyes-optical-specialist-taking-care-about-eyesight.jpg","width":1500,"height":956,"caption":"ophtalmologue auscultant un patient dans un cabinet"},{"@type":"BreadcrumbList","@id":"https:\/\/brm-conseil.fr\/fr\/2022\/08\/15\/emploi-ophtalmologue-en-france-comment-trouver-un-poste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/brm-conseil.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Emploi ophtalmologue en France : comment trouver un poste ?"}]},{"@type":"WebSite","@id":"https:\/\/brm-conseil.fr\/fr\/#website","url":"https:\/\/brm-conseil.fr\/fr\/","name":"BrmConseil","description":"Specialista in reclutamento medico","publisher":{"@id":"https:\/\/brm-conseil.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brm-conseil.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/brm-conseil.fr\/fr\/#organization","name":"BRM Conseil","url":"https:\/\/brm-conseil.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/logo-brmconseil.png","contentUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/logo-brmconseil.png","width":420,"height":66,"caption":"BRM Conseil"},"image":{"@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/person\/306310a2b7c316650384cfd4a81211ed","name":"genone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","caption":"genone"},"url":"https:\/\/brm-conseil.fr\/it\/author\/genone\/"}]}},"_links":{"self":[{"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/comments?post=11154"}],"version-history":[{"count":6,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154\/revisions"}],"predecessor-version":[{"id":11815,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/posts\/11154\/revisions\/11815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/media\/11155"}],"wp:attachment":[{"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/media?parent=11154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/categories?post=11154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brm-conseil.fr\/it\/wp-json\/wp\/v2\/tags?post=11154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}