{"id":380,"date":"2018-12-12T16:43:28","date_gmt":"2018-12-12T15:43:28","guid":{"rendered":"http:\/\/brm-conseil.fr\/?p=380"},"modified":"2020-02-11T17:30:03","modified_gmt":"2020-02-11T16:30:03","slug":"professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats","status":"publish","type":"post","link":"https:\/\/brm-conseil.fr\/es\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/","title":{"rendered":"Profesionales sanitarios: \u00bfcu\u00e1l es el m\u00e9todo de selecci\u00f3n de candidatos?"},"content":{"rendered":"\n\n[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; background_image=\u00a0\u00bbhttps:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/computer-1149148_1280-1080&#215;675.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb150px||150px\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; background_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb custom_margin=\u00a0\u00bb-150px||\u00a0\u00bb custom_padding=\u00a0\u00bb|||||\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime;][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; background_color=\u00a0\u00bb#0c71c3&Prime; custom_padding=\u00a0\u00bb30px|20px|30px|20px\u00a0\u00bb][et_pb_post_title categories=\u00a0\u00bboff\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb3.25.2&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_text_align=\u00a0\u00bbleft\u00a0\u00bb title_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb title_font_size=\u00a0\u00bb30px\u00a0\u00bb meta_font=\u00a0\u00bb||||||||\u00a0\u00bb meta_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb title_font_size_tablet=\u00a0\u00bb20px\u00a0\u00bb title_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime; custom_margin=\u00a0\u00bb-100px||\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; custom_margin=\u00a0\u00bb|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]Le recrutement d\u2019un candidat est une \u00e9tape primordiale pour les organisations. Un recrutement efficace permet d\u2019identifier rapidement les candidats \u00e0 fort potentiel, c\u2019est pourquoi il est recommand\u00e9 de se tourner vers un cabinet sp\u00e9cialis\u00e9 dans le recrutement et la gestion des professionnels de la sant\u00e9 pour assurer une embauche \u00e0 la hauteur de la fiche de poste.\n\nLes recrutements strat\u00e9giques sont synonymes de performance et d\u00e9veloppement pour votre entreprise, alors confiez-les \u00e0 des professionnels qui sauront suivre une m\u00e9thodologie \u00e9prouv\u00e9e, personnalis\u00e9e et adapt\u00e9e \u00e0 vos besoins ![\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb50px|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]<h2>L\u2019alliance de l\u2019expertise scientifique et de l\u2019\u00e9valuation des talents\n<\/h2>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; custom_margin=\u00a0\u00bb-15px|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]Pour recruter des professionnels de la sant\u00e9, il est primordial de bien conna\u00eetre les ficelles, les contraintes et les enjeux de ce secteur qui poss\u00e8de nombre de particularit\u00e9s. C\u2019est pourquoi il est conseill\u00e9 de confier vos recrutements \u00e0 un cabinet qui poss\u00e8de une solide double expertise aussi bien dans le secteur de la sant\u00e9 que dans le recrutement de talents[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]<h2>Une fiche de poste pr\u00e9cise et exhaustive<\/h2>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; custom_margin=\u00a0\u00bb-15px|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]En recrutement, rien ne sert de courir, il faut partir \u00e0 point. Lorsque vous avez un poste \u00e0 pourvoir, il ne faut pas sauter sur le premier candidat venu, vous risquez d\u2019\u00eatre d\u00e9\u00e7us par la suite. Au contraire, mieux vaut prendre le temps d\u2019identifier clairement les comp\u00e9tences, savoir-faire et savoir-\u00eatre requis. Pour cela, il convient de bien analyser le besoin et constituer clairement la fiche de poste. Quelles sont les missions g\u00e9n\u00e9rales, r\u00e9guli\u00e8res et ponctuelles ? Quels savoir-faire, comp\u00e9tences et connaissances sont requis ? Le candidat doit-il justifier d\u2019une exp\u00e9rience particuli\u00e8re ?\n\nPosez \u00e9galement le p\u00e9rim\u00e8tre du poste : quels seront le grade du candidat et sa position dans la structure ? Quelles sont les liaisons hi\u00e9rarchiques, quelles sont les liaisons fonctionnelles ? Le candidat exercera-t-il sa fonction dans un secteur intra-hospitalier, extra-hospitalier ? Faites aussi le point sur les risques professionnels li\u00e9s \u00e0 l\u2019activit\u00e9 et les mesures de pr\u00e9vention prises face \u00e0 ces risques[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25.2&Prime;][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]<h2>L\u2019entretien, le moment cl\u00e9 du recrutement<\/h2>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb3.25.2&Prime; custom_margin=\u00a0\u00bb-15px|100px||100px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||0px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]Une fois votre fiche de poste clairement d\u00e9finie, vous pouvez passer au recrutement. Que vous proc\u00e9diez \u00e0 un recrutement en interne ou en externe, cette \u00e9tape est d\u00e9cisive aussi bien pour le recruteur que pour le candidat. Le recruteur va poser des questions au candidat, mais aussi faire attention aux petits d\u00e9tails qui donnent des indices sur la personnalit\u00e9 du candidat : disponibilit\u00e9, ma\u00eetrise de soi, assurance\u2026\n\nToutes ces qualit\u00e9s sont indispensables dans le secteur de la sant\u00e9, et un bon recruteur peut les d\u00e9celer d\u2019un seul coup d\u2019\u0153il. Les questions pos\u00e9es durant l\u2019entretien permettent de valider les connaissances du candidat, mais aussi d\u2019en savoir plus sur son savoir-\u00eatre. Un test de personnalit\u00e9 peut venir compl\u00e9ter l\u2019entretien pour permettre de mieux cerner le comportement et la motivation du candidat.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n","protected":false},"excerpt":{"rendered":"<p>Le recrutement d\u2019un candidat est une \u00e9tape primordiale pour les organisations. Un recrutement efficace permet d\u2019identifier rapidement les candidats \u00e0 fort potentiel, c\u2019est pourquoi il est recommand\u00e9 de se tourner vers un cabinet sp\u00e9cialis\u00e9 dans le recrutement et la gestion des professionnels de la sant\u00e9 pour assurer une embauche \u00e0 la hauteur de la fiche [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[159],"tags":[],"class_list":["post-380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annonces-medicales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil\" \/>\n<meta property=\"og:description\" content=\"Le recrutement d\u2019un candidat est une \u00e9tape primordiale pour les organisations. Un recrutement efficace permet d\u2019identifier rapidement les candidats \u00e0 fort potentiel, c\u2019est pourquoi il est recommand\u00e9 de se tourner vers un cabinet sp\u00e9cialis\u00e9 dans le recrutement et la gestion des professionnels de la sant\u00e9 pour assurer une embauche \u00e0 la hauteur de la fiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380\" \/>\n<meta property=\"og:site_name\" content=\"BRM Conseil\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-12T15:43:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T16:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2020\/01\/LinkedIn_Brm-Conseil.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"genone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"genone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/\"},\"author\":{\"name\":\"genone\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/person\\\/306310a2b7c316650384cfd4a81211ed\"},\"headline\":\"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ?\",\"datePublished\":\"2018-12-12T15:43:28+00:00\",\"dateModified\":\"2020-02-11T16:30:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/\"},\"wordCount\":898,\"publisher\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/computer-1149148_1280-1080x675.jpg\",\"articleSection\":[\"Annonces m\u00e9dicales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/\",\"name\":\"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/computer-1149148_1280-1080x675.jpg\",\"datePublished\":\"2018-12-12T15:43:28+00:00\",\"dateModified\":\"2020-02-11T16:30:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/computer-1149148_1280-1080x675.jpg\",\"contentUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/computer-1149148_1280-1080x675.jpg\",\"width\":1080,\"height\":675,\"caption\":\"m\u00e9decine-travail\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/it\\\/2018\\\/12\\\/12\\\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\",\"name\":\"BrmConseil\",\"description\":\"Sp\u00e9cialiste du recrutement m\u00e9dical\",\"publisher\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#organization\",\"name\":\"BRM Conseil\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-brmconseil.png\",\"contentUrl\":\"https:\\\/\\\/brm-conseil.fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-brmconseil.png\",\"width\":420,\"height\":66,\"caption\":\"BRM Conseil\"},\"image\":{\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brm-conseil.fr\\\/fr\\\/#\\\/schema\\\/person\\\/306310a2b7c316650384cfd4a81211ed\",\"name\":\"genone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g\",\"caption\":\"genone\"},\"url\":\"https:\\\/\\\/brm-conseil.fr\\\/es\\\/author\\\/genone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380","og_locale":"es_ES","og_type":"article","og_title":"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil","og_description":"Le recrutement d\u2019un candidat est une \u00e9tape primordiale pour les organisations. Un recrutement efficace permet d\u2019identifier rapidement les candidats \u00e0 fort potentiel, c\u2019est pourquoi il est recommand\u00e9 de se tourner vers un cabinet sp\u00e9cialis\u00e9 dans le recrutement et la gestion des professionnels de la sant\u00e9 pour assurer une embauche \u00e0 la hauteur de la fiche [&hellip;]","og_url":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380","og_site_name":"BRM Conseil","article_published_time":"2018-12-12T15:43:28+00:00","article_modified_time":"2020-02-11T16:30:03+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2020\/01\/LinkedIn_Brm-Conseil.png","type":"image\/jpeg"}],"author":"genone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"genone","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#article","isPartOf":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/"},"author":{"name":"genone","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/person\/306310a2b7c316650384cfd4a81211ed"},"headline":"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ?","datePublished":"2018-12-12T15:43:28+00:00","dateModified":"2020-02-11T16:30:03+00:00","mainEntityOfPage":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/"},"wordCount":898,"publisher":{"@id":"https:\/\/brm-conseil.fr\/fr\/#organization"},"image":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#primaryimage"},"thumbnailUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/computer-1149148_1280-1080x675.jpg","articleSection":["Annonces m\u00e9dicales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/","url":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/","name":"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ? - BRM Conseil","isPartOf":{"@id":"https:\/\/brm-conseil.fr\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#primaryimage"},"image":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#primaryimage"},"thumbnailUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/computer-1149148_1280-1080x675.jpg","datePublished":"2018-12-12T15:43:28+00:00","dateModified":"2020-02-11T16:30:03+00:00","breadcrumb":{"@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#primaryimage","url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/computer-1149148_1280-1080x675.jpg","contentUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/computer-1149148_1280-1080x675.jpg","width":1080,"height":675,"caption":"m\u00e9decine-travail"},{"@type":"BreadcrumbList","@id":"https:\/\/brm-conseil.fr\/it\/2018\/12\/12\/professionnels-de-la-sante-quelle-est-la-methode-de-recrutement-pour-selectionner-les-candidats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/brm-conseil.fr\/fr\/"},{"@type":"ListItem","position":2,"name":"Professionnels de la sant\u00e9 : quelle est la m\u00e9thode de recrutement pour s\u00e9lectionner les candidats ?"}]},{"@type":"WebSite","@id":"https:\/\/brm-conseil.fr\/fr\/#website","url":"https:\/\/brm-conseil.fr\/fr\/","name":"BrmConseil","description":"Especialista en contrataci\u00f3n m\u00e9dica","publisher":{"@id":"https:\/\/brm-conseil.fr\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/brm-conseil.fr\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/brm-conseil.fr\/fr\/#organization","name":"BRM Conseil","url":"https:\/\/brm-conseil.fr\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/logo-brmconseil.png","contentUrl":"https:\/\/brm-conseil.fr\/wp-content\/uploads\/2019\/06\/logo-brmconseil.png","width":420,"height":66,"caption":"BRM Conseil"},"image":{"@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/brm-conseil.fr\/fr\/#\/schema\/person\/306310a2b7c316650384cfd4a81211ed","name":"genone","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dd236d8c3fbc6bf06eaf51e430e0f0d8231baf97b2c90e2513c961a2e0761c5?s=96&d=mm&r=g","caption":"genone"},"url":"https:\/\/brm-conseil.fr\/es\/author\/genone\/"}]}},"_links":{"self":[{"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/comments?post=380"}],"version-history":[{"count":5,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380\/revisions"}],"predecessor-version":[{"id":1817,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/posts\/380\/revisions\/1817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/media\/273"}],"wp:attachment":[{"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/media?parent=380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/categories?post=380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brm-conseil.fr\/es\/wp-json\/wp\/v2\/tags?post=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}